{"id":192707,"date":"2024-02-20T12:45:53","date_gmt":"2024-02-20T11:45:53","guid":{"rendered":"https:\/\/liora.io\/de\/?p=192707"},"modified":"2026-08-04T02:07:24","modified_gmt":"2026-08-04T00:07:24","slug":"shap-fuer-die-interpretierbarkeit-von-ki-modellen","status":"publish","type":"post","link":"https:\/\/liora.io\/de\/shap-fuer-die-interpretierbarkeit-von-ki-modellen","title":{"rendered":"SHAP, f\u00fcr die Interpretierbarkeit von KI-Modellen"},"content":{"rendered":"\n<p><strong>Die F\u00e4higkeit, Entscheidungen zu verstehen und zu erkl\u00e4ren, die von Modellen der K\u00fcnstlichen Intelligenz oder des Machine Learning getroffen werden, ist von gr\u00f6\u00dfter Bedeutung geworden. Diese hochentwickelten Technologien werden zunehmend in kritische Bereiche wie das Gesundheitswesen, die Finanzwelt oder die Sicherheit integriert. L\u00f6sungen wie SHAP (SHapley Additive exPlanations) erleben einen rasanten Aufschwung.<\/strong><\/p>\n\n\n\n<p><strong>SHAP<\/strong> basiert auf den Konzepten der kooperativen Spieltheorie und bietet eine rigorose und intuitive Methode, um die Modellvorhersagen in die individuellen Beitr\u00e4ge der einzelnen Merkmale zu zerlegen.<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"theoretische-grundlagen-von-shap\">Theoretische Grundlagen von SHAP<\/h2>\n\n\n\n<p>Es ist notwendig, die <strong>theoretischen Wurzeln von SHAP ein wenig zu analysieren<\/strong>, um seinen Mehrwert zu verstehen, aber auch den Grund, warum es effektiv ist, um manchmal komplexe Modelle zu interpretieren.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\" style=\"width:512px;max-width:100%;margin-top:32px;margin-right:auto;margin-bottom:32px;margin-left:auto\"><img alt=\"Illustration zu \u201eTheoretische Grundlagen von SHAP\u201c\" decoding=\"async\" height=\"512\" loading=\"lazy\" src=\"https:\/\/liora.io\/app\/uploads\/2024\/01\/image1-2.png\" style=\"width:512px;max-width:100%;height:auto\" width=\"512\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"kooperative-spieltheorie\">Kooperative Spieltheorie<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex is-content-justification-center wp-container-core-buttons-is-layout-5ee10de4\" style=\"margin-top:32px;margin-bottom:32px\"><div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/liora.io\/de\/weiterbildung\/data-ki\/machine-learning-engineer\">Alles \u00fcber SHAP lernen<\/a><\/div><\/div>\n\n\n\n<p>Diese Theorie, ein Zweig der Spieltheorie, konzentriert sich auf die Analyse von Strategien f\u00fcr Gruppen von Akteuren, die sich zusammenschlie\u00dfen k\u00f6nnen, um Kooperationen zu bilden und Belohnungen zu teilen.<\/p>\n\n\n\n<p>Im Zentrum dieser Theorie steht der Begriff des &#8222;fairen Wertes&#8220;, eine M\u00f6glichkeit, Gewinne (oder Verluste) unter den Teilnehmern in einer Weise zu verteilen, die ihren individuellen Beitrag widerspiegelt. In diesem Zusammenhang ist der<strong> Shapley-Wert zu sehen.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\" style=\"width:512px;max-width:100%;margin-top:32px;margin-right:auto;margin-bottom:32px;margin-left:auto\"><img alt=\"Illustration zu \u201eKooperative Spieltheorie\u201c\" decoding=\"async\" height=\"512\" loading=\"lazy\" src=\"https:\/\/liora.io\/app\/uploads\/2024\/01\/image6-2.png\" style=\"width:512px;max-width:100%;height:auto\" width=\"512\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"der-shapley-wert\">Der Shapley-Wert<\/h3>\n\n\n\n<p>Dies ist ein <a href=\"https:\/\/liora.io\/de\/expected-goals-die-mathematik-dahinter-verstehen\">mathematisches Konzept<\/a>, das 1953 von Lloyd Shapley eingef\u00fchrt wurde und dazu dient, den fairen Anteil jedes Spielers in einem kooperativen Spiel zu bestimmen. Sie wird berechnet, indem man alle m\u00f6glichen Permutationen von Spielern ber\u00fccksichtigt und den marginalen Einfluss jedes Spielers bewertet, wenn er sich einer Koalition anschlie\u00dft. Mit anderen Worten, sie misst den durchschnittlichen Beitrag eines Spielers zu einer Koalition unter Ber\u00fccksichtigung aller m\u00f6glichen Kombinationen, in denen dieser Spieler einen Beitrag leisten k\u00f6nnte.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\" style=\"width:512px;max-width:100%;margin-top:32px;margin-right:auto;margin-bottom:32px;margin-left:auto\"><img alt=\"Illustration zu \u201eDer Shapley-Wert\u201c\" decoding=\"async\" height=\"512\" loading=\"lazy\" src=\"https:\/\/liora.io\/app\/uploads\/2024\/01\/image5-3.png\" style=\"width:512px;max-width:100%;height:auto\" width=\"512\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"verbindung-mit-shap\">Verbindung mit SHAP<\/h3>\n\n\n\n<p>Im Zusammenhang mit maschinellem Lernen verwendet <strong>SHAP den Shapley-Wert,<\/strong> um jedem Merkmal in einem <a href=\"https:\/\/liora.io\/de\/folgen-und-reihen-mathe-das-prinzip-verstehen\">Vorhersagemodell<\/a> einen &#8222;Wichtigkeitswert&#8220; zuzuweisen. Jedes Merkmal einer Dateninstanz wird als &#8222;Spieler&#8220; in einem kooperativen Spiel betrachtet, bei dem der &#8222;Gewinn&#8220; die Vorhersage des Modells ist.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\" style=\"width:512px;max-width:100%;margin-top:32px;margin-right:auto;margin-bottom:32px;margin-left:auto\"><img alt=\"Illustration zu \u201eVerbindung mit SHAP\u201c\" decoding=\"async\" height=\"512\" loading=\"lazy\" src=\"https:\/\/liora.io\/app\/uploads\/2024\/01\/image2-2.png\" style=\"width:512px;max-width:100%;height:auto\" width=\"512\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"auswirkungen-des-shapley-wertes-auf-die-ki\">Auswirkungen des Shapley-Wertes auf die KI<\/h3>\n\n\n\n<p>Dieser Wert stellt einen bedeutenden Fortschritt bei der <a href=\"https:\/\/liora.io\/de\/ki-trainieren-ohne-daten-mit-dieser-neuen-technik-ist-es-moeglich\">Interpretierbarkeit von KI-Modellen<\/a> dar. Er erm\u00f6glicht es nicht nur, die Auswirkungen jedes Merkmals fair und einheitlich zu quantifizieren, sondern bietet auch eine Transparenz, die dabei hilft,<a href=\"https:\/\/liora.io\/de\/featuretools-das-werkzeug-das-das-feature-engineering-mit-machine-learning-automatisiert\"> Vertrauen in maschinelle Lernmodelle aufzubauen.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"wie-funktioniert-shap\">Wie funktioniert SHAP?<\/h2>\n\n\n\n<p>Das Herzst\u00fcck von <strong>SHAP<\/strong> ist die Idee, eine bestimmte Vorhersage in einen Satz von Werten zu zerlegen, die jedem Eingabemerkmal zugewiesen werden.<\/p>\n\n\n\n<p>Diese Werte werden so berechnet, dass sie den Einfluss jedes Merkmals auf die Abweichung zwischen der aktuellen Vorhersage und dem Durchschnitt der Vorhersagen \u00fcber den Datensatz widerspiegeln.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex is-content-justification-center wp-container-core-buttons-is-layout-5ee10de4\" style=\"margin-top:32px;margin-bottom:32px\"><div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/liora.io\/de\/weiterbildung\/data-ki\/machine-learning-engineer\">Apprendre \u00e0 utiliser SHAP<\/a><\/div><\/div>\n\n\n\n<p>Um dies zu erreichen, untersucht<strong> SHAP<\/strong> alle m\u00f6glichen Kombinationen von Merkmalen und deren Beitr\u00e4ge zur Vorhersage. Dieser Prozess nutzt den Shapley-Wert, den wir zuvor besprochen haben, um eine faire und genaue Verteilung der Auswirkungen unter den Merkmalen zu gew\u00e4hrleisten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"nehmen-wir-ein-beispiel\">Nehmen wir ein Beispiel<\/h3>\n\n\n\n<p>Stellen wir uns ein Vorhersagemodell vor, das in der Finanzbranche zur Bewertung des Kreditrisikos eingesetzt wird. SHAP kann aufdecken, wie Merkmale wie der Kredit-Score, das Jahreseinkommen und die R\u00fcckzahlungshistorie zur endg\u00fcltigen Entscheidung des Modells beitragen. Wenn einem Kunden ein Kredit verweigert wird, kann SHAP aufzeigen, welche Merkmale diese negative Entscheidung am st\u00e4rksten beeinflusst haben, und so relevante Indikatoren liefern.<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"verwendung-mit-python\">Verwendung mit Python<\/h2>\n\n\n\n<p><a href=\"https:\/\/liora.io\/de\/top-10-der-python-bibliotheken-fur-data-scientists\">Python bietet eine Bibliothek<\/a> f\u00fcr<strong> SHAP<\/strong>. Diese erm\u00f6glicht es den Nutzern, die Vorteile von SHAP f\u00fcr die Interpretierbarkeit von Modellen voll auszusch\u00f6pfen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"installation\">Installation<\/h3>\n\n\n\n<p>Der erste Schritt ist nat\u00fcrlich die Installation der Bibliothek.<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>\t\t\t\t\n\t\t\t\t\tpip install shap\n\t\t\t\t\n\t\t\t<\/code><\/pre>\n\n\n\n<p>Nach der Installation musst du sie nur noch in deine Umgebung importieren :<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>\t\t\t\t\n\t\t\t\t\timport shap\n\t\t\t\t\n\t\t\t<\/code><\/pre>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"vorbereitung-der-daten\">Vorbereitung der Daten<\/h3>\n\n\n\n<p>Angenommen, du hast ein bereits trainiertes Machine-Learning-Modell, z. B. ein Zufallswaldmodell f\u00fcr die Klassifizierung (RandomForestClassifier). Dann ben\u00f6tigst du einen <a href=\"https:\/\/liora.io\/de\/datasets-top-5-websites-fuer-qualitativ-hochwertige-datensaetze\">Datensatz f\u00fcr die Analyse :<\/a><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>\t\t\t\t\n\t\t\t\t\tfrom sklearn.model_selection import train_test_split\nfrom sklearn.ensemble import RandomForestClassifier\nimport pandas as pd\n# Load and prepare datas\ndata = pd.read_csv('my_amazing_dataset.csv')\nX = data.drop('target', axis=1)\ny = data['target']\n# Split train and test set\nX_train, X_test, y_train, y_test = train_test_split(X, y, test_size=0.2, random_state=42)\n# Train the model\nmodel = RandomForestClassifier(random_state=42)\nmodel.fit(X_train, y_train)\n\t\t\t\t\n\t\t\t<\/code><\/pre>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"shap-analyse\">SHAP-Analyse<\/h3>\n\n\n\n<p>Nachdem du das Modell trainiert hast, kannst du mithilfe von <strong>SHAP die Auswirkungen der Merkmale analysieren.<\/strong> F\u00fcr die Fortsetzung dieses Beispiels k\u00f6nnen wir den Explainer Tree verwenden.<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>\t\t\t\t\n\t\t\t\t\t# Create Explainer Tree\nexplainer = shap.TreeExplainer(model)\n# Compute SHAP Values on the test set\nshap_values = explainer.shap_values(X_test)\n\t\t\t\t\n\t\t\t<\/code><\/pre>\n\n\n\n\n\n<h3 class=\"wp-block-heading\" id=\"visualisierung-der-ergebnisse\">Visualisierung der Ergebnisse<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex is-content-justification-center wp-container-core-buttons-is-layout-5ee10de4\" style=\"margin-top:32px;margin-bottom:32px\"><div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/liora.io\/de\/weiterbildung\/data-ki\/data-engineer\">Bilde dich in SHAP weiter<\/a><\/div><\/div>\n\n\n\n<p><strong>SHAP<\/strong> bietet nat\u00fcrlich verschiedene Visualisierungsoptionen, um die Ergebnisse zu interpretieren. Um eine Zusammenfassung der Wichtigkeit von Merkmalen zu erhalten, kannst du zum Beispiel :<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>\t\t\t\t\n\t\t\t\t\tshap.summary_plot(shap_values, X_test)\n\t\t\t\t\n\t\t\t<\/code><\/pre>\n\n\n\n<figure class=\"wp-block-image size-full\" style=\"margin-top:32px;margin-bottom:32px\"><img alt=\"Illustration zu \u201eVisualisierung der Ergebnisse\u201c\" decoding=\"async\" height=\"271\" loading=\"lazy\" src=\"https:\/\/liora.io\/app\/uploads\/2024\/01\/image7-2.png\" style=\"width:100%;height:auto\" width=\"802\"\/><\/figure>\n\n\n\n<p>Es ist auch m\u00f6glich, die Auswirkungen eines bestimmten Merkmals zu untersuchen:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>\t\t\t\t\n\t\t\t\t\t# Need to initialize javascript in order to display the plots\nshap.initjs()\n# View impact\nshap.plots.force(explainer.expected_value[0], shap_values[0])\n\t\t\t\t\n\t\t\t<\/code><\/pre>\n\n\n\n<figure class=\"wp-block-image size-full\" style=\"margin-top:32px;margin-bottom:32px\"><img alt=\"Illustration zu \u201eVisualisierung der Ergebnisse\u201c\" decoding=\"async\" height=\"415\" loading=\"lazy\" src=\"https:\/\/liora.io\/app\/uploads\/2024\/01\/image4-2.png\" style=\"width:100%;height:auto\" width=\"962\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"fazit\">Fazit<\/h2>\n\n\n\n<p><strong>SHAP (SHapley Additive exPlanations)<\/strong> ist ein leistungsf\u00e4higes und vielseitiges Werkzeug f\u00fcr die Interpretierbarkeit von Machine-Learning-Modellen. Basierend auf den Prinzipien der kooperativen Spieltheorie und des Shapley-Wertes bietet es eine rigorose Methode, um die Beitr\u00e4ge einzelner Merkmale in den Vorhersagen eines Modells aufzuschl\u00fcsseln und zu verstehen.<\/p>\n\n\n\n<p>Die Verwendung der<strong> SHAP-Bibliothek in Python zeigt,<\/strong> wie einfach sie sich in den Data-Science-Workflow integrieren und implementieren l\u00e4sst. Da k\u00fcnstliche Intelligenz immer allgegenw\u00e4rtiger wird, kann man es sich au\u00dferdem nicht leisten, die Interpretierbarkeit von Modellen zu untersch\u00e4tzen.<\/p>\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Die F\u00e4higkeit, Entscheidungen zu verstehen und zu erkl\u00e4ren, die von Modellen der K\u00fcnstlichen Intelligenz oder des Machine Learning getroffen werden, ist von gr\u00f6\u00dfter Bedeutung geworden. Diese hochentwickelten Technologien werden zunehmend in kritische Bereiche wie das Gesundheitswesen, die Finanzwelt oder die Sicherheit integriert. L\u00f6sungen wie SHAP (SHapley Additive exPlanations) erleben einen rasanten Aufschwung. SHAP basiert auf [&hellip;]<\/p>\n","protected":false},"author":76,"featured_media":192709,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"_acf_changed":false,"editor_notices":[],"footnotes":""},"categories":[2472],"class_list":["post-192707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-data-ki"],"acf":[],"_links":{"self":[{"href":"https:\/\/liora.io\/de\/wp-json\/wp\/v2\/posts\/192707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liora.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/liora.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/liora.io\/de\/wp-json\/wp\/v2\/users\/76"}],"replies":[{"embeddable":true,"href":"https:\/\/liora.io\/de\/wp-json\/wp\/v2\/comments?post=192707"}],"version-history":[{"count":4,"href":"https:\/\/liora.io\/de\/wp-json\/wp\/v2\/posts\/192707\/revisions"}],"predecessor-version":[{"id":224613,"href":"https:\/\/liora.io\/de\/wp-json\/wp\/v2\/posts\/192707\/revisions\/224613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/liora.io\/de\/wp-json\/wp\/v2\/media\/192709"}],"wp:attachment":[{"href":"https:\/\/liora.io\/de\/wp-json\/wp\/v2\/media?parent=192707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/liora.io\/de\/wp-json\/wp\/v2\/categories?post=192707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}